{"id":7321,"date":"2018-07-03T10:16:58","date_gmt":"2018-07-03T08:16:58","guid":{"rendered":"http:\/\/beta.veglio.com\/emozioniluminose\/?post_type=product&#038;p=7321"},"modified":"2023-08-25T09:06:51","modified_gmt":"2023-08-25T07:06:51","slug":"album-seppiolina","status":"publish","type":"product","link":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/album-seppiolina\/","title":{"rendered":"Album Seppiolina"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Fornisce luce diffusa per mezzo di una lampadina bispina. E\u2019 utilizzabile con lampadine a LED. E\u2019 realizzata in vetro borosilicato soffiato e formato a mano.<\/p>\n<p>Designer: Pepe Tanzi<\/p>\n<div class=\"scheda-prodotto\"><a href=\"https:\/\/album.it\/it\/product\/corpi_illuminanti\/14822\" target=\"_blank\" rel=\"noopener\">Vai alla scheda prodotto<\/a><\/div>\n<div>\n<p>Dove acquistare Album da Vegliolux, un marchio del gruppo Idrocentro:<\/p>\n<p>Piemonte:<\/p>\n<p>\u2013 Torino:<br \/>\n\u2014 Filiale principale: Via Sandro Botticelli, 151\/a, 10154 Torino TO<br \/>\n\u2014 Orbassano: Corso Orbassano, 400, 10137 Torino TO<br \/>\n\u2014 Centro: Corso Sommeiller, 15\/D, 10128 Torino TO<br \/>\n\u2014 Corso Lecce: Corso Lecce, 56, 10143 Torino TO<\/p>\n<p>\u2013 Volpiano: Via Venezia, 12, 10088 Volpiano TO<\/p>\n<p>\u2013 Asti Ovest: Corso Torino, 43, 14100 Asti AT<\/p>\n<p>\u2013 Borgaretto: Via Rond\u00f2 Bernardo, 30, 10092 Beinasco TO<\/p>\n<p>\u2013 Borgo Gesso: Via Torre Acceglio, 26, 12100 Cuneo CN<\/p>\n<p>\u2013 Carmagnola: Via Sommariva, 14, 10022 Carmagnola TO<\/p>\n<p>\u2013 Caselle: Str. Ciri\u00e8, 175, 10072 Caselle torinese TO<\/p>\n<p>\u2013 Chieri: Via XXV Aprile, 8, 10023 Chieri TO<\/p>\n<p>\u2013 Pinerolo: Via Saluzzo, 165, 10064 Pinerolo TO<\/p>\n<p>\u2013 Settimo: Str. S. Giorgio, 43, 10036 Settimo Torinese TO<\/p>\n<p>\u2013 Susa: Corso Stati Uniti, 89, 10059 Susa TO<\/p>\n<p>\u2013 Torre San Giorgio: Via Circonvallazione G. Giolitti, 100, 12030 Torre San Giorgio CN (Sede gruppo Idrocentro)<\/p>\n<p>\u2013 Castelnuovo Calcea: Via Opessina, 14040 Castenuovo Calcea, AT<\/p>\n<p>Liguria:<\/p>\n<p>\u2013 Genova Sturla: Via Tabarca, 44, 16147 Genova GE<\/p>\n<p>\u2013 Vado Ligure: Via Leopardi, 4, 17047 Vado Ligure SV<\/p>\n<p>\u2013 Andora: Via Merula, 22, 17051 Andora SV<\/p>\n<p>Lombardia:<\/p>\n<p>\u2013 Cornaredo: Via Napoli, 7, 20010 Cornaredo MI<\/p>\n<p>Valle d&#8217;Aosta:<\/p>\n<p>\u2013 Quart: Localit\u00e0 Amerique, 3, 11100 Villair-Amerique AO<\/p>\n<\/div>\n","protected":false},"featured_media":7322,"template":"","meta":[],"product_brand":[],"product_cat":[255,148],"product_tag":[165],"class_list":{"0":"post-7321","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-album","7":"product_cat-incassi","8":"product_tag-album","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Album Seppiolina - Vegliolux<\/title>\n<meta name=\"description\" content=\"Da Vegliolux, un marchio del gruppo Idrocentro, puoi trovare Album Seppiolina . Da Vegliolux la migliore illuminazione\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/album-seppiolina\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Album Seppiolina - Vegliolux\" \/>\n<meta property=\"og:description\" content=\"Da Vegliolux, un marchio del gruppo Idrocentro, puoi trovare Album Seppiolina . Da Vegliolux la migliore illuminazione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/album-seppiolina\/\" \/>\n<meta property=\"og:site_name\" content=\"Vegliolux\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vegliolux\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-25T07:06:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2018\/07\/Album-Seppiolina-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"973\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/album-seppiolina\\\/\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/album-seppiolina\\\/\",\"name\":\"Album Seppiolina - Vegliolux\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/album-seppiolina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/album-seppiolina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Album-Seppiolina-01.jpg\",\"datePublished\":\"2018-07-03T08:16:58+00:00\",\"dateModified\":\"2023-08-25T07:06:51+00:00\",\"description\":\"Da Vegliolux, un marchio del gruppo Idrocentro, puoi trovare Album Seppiolina . Da Vegliolux la migliore illuminazione\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/album-seppiolina\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/album-seppiolina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/album-seppiolina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Album-Seppiolina-01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Album-Seppiolina-01.jpg\",\"width\":800,\"height\":973,\"caption\":\"Album Seppiolina: lampadario applique soffitto led da Vegliolux, un marchio del gruppo Idrocentro, gli specialisti di illuminazione e elettroforniture. Acquista nei nostri punti vendita di Piemonte, Liguria, Lombardia e Valle d'Aosta\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/album-seppiolina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Album Seppiolina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#website\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/\",\"name\":\"Vegliolux - Illuminazione Torino\",\"description\":\"Emozioni luminose\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#organization\",\"name\":\"Vegliolux - Illuminazione Torino\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Vegliolux-Sommeiller.jpg\",\"contentUrl\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Vegliolux-Sommeiller.jpg\",\"width\":1080,\"height\":720,\"caption\":\"Vegliolux - Illuminazione Torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vegliolux\",\"https:\\\/\\\/www.instagram.com\\\/vegliolux\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vegliolux\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Album Seppiolina - Vegliolux","description":"Da Vegliolux, un marchio del gruppo Idrocentro, puoi trovare Album Seppiolina . Da Vegliolux la migliore illuminazione","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/album-seppiolina\/","og_locale":"it_IT","og_type":"article","og_title":"Album Seppiolina - Vegliolux","og_description":"Da Vegliolux, un marchio del gruppo Idrocentro, puoi trovare Album Seppiolina . Da Vegliolux la migliore illuminazione","og_url":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/album-seppiolina\/","og_site_name":"Vegliolux","article_publisher":"https:\/\/www.facebook.com\/Vegliolux","article_modified_time":"2023-08-25T07:06:51+00:00","og_image":[{"width":800,"height":973,"url":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2018\/07\/Album-Seppiolina-01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/album-seppiolina\/","url":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/album-seppiolina\/","name":"Album Seppiolina - Vegliolux","isPartOf":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/album-seppiolina\/#primaryimage"},"image":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/album-seppiolina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2018\/07\/Album-Seppiolina-01.jpg","datePublished":"2018-07-03T08:16:58+00:00","dateModified":"2023-08-25T07:06:51+00:00","description":"Da Vegliolux, un marchio del gruppo Idrocentro, puoi trovare Album Seppiolina . Da Vegliolux la migliore illuminazione","breadcrumb":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/album-seppiolina\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/album-seppiolina\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/album-seppiolina\/#primaryimage","url":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2018\/07\/Album-Seppiolina-01.jpg","contentUrl":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2018\/07\/Album-Seppiolina-01.jpg","width":800,"height":973,"caption":"Album Seppiolina: lampadario applique soffitto led da Vegliolux, un marchio del gruppo Idrocentro, gli specialisti di illuminazione e elettroforniture. Acquista nei nostri punti vendita di Piemonte, Liguria, Lombardia e Valle d'Aosta"},{"@type":"BreadcrumbList","@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/album-seppiolina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.veglio.com\/emozioniluminose\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/www.veglio.com\/emozioniluminose\/prodotti\/"},{"@type":"ListItem","position":3,"name":"Album Seppiolina"}]},{"@type":"WebSite","@id":"https:\/\/www.veglio.com\/emozioniluminose\/#website","url":"https:\/\/www.veglio.com\/emozioniluminose\/","name":"Vegliolux - Illuminazione Torino","description":"Emozioni luminose","publisher":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.veglio.com\/emozioniluminose\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.veglio.com\/emozioniluminose\/#organization","name":"Vegliolux - Illuminazione Torino","url":"https:\/\/www.veglio.com\/emozioniluminose\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.veglio.com\/emozioniluminose\/#\/schema\/logo\/image\/","url":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2022\/09\/Vegliolux-Sommeiller.jpg","contentUrl":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2022\/09\/Vegliolux-Sommeiller.jpg","width":1080,"height":720,"caption":"Vegliolux - Illuminazione Torino"},"image":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vegliolux","https:\/\/www.instagram.com\/vegliolux\/","https:\/\/www.linkedin.com\/company\/vegliolux"]}]}},"_links":{"self":[{"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product\/7321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/media\/7322"}],"wp:attachment":[{"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/media?parent=7321"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product_brand?post=7321"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product_cat?post=7321"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product_tag?post=7321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}