{"id":7971,"date":"2018-07-11T16:00:40","date_gmt":"2018-07-11T14:00:40","guid":{"rendered":"http:\/\/beta.veglio.com\/emozioniluminose\/?post_type=product&#038;p=7971"},"modified":"2023-08-25T11:05:42","modified_gmt":"2023-08-25T09:05:42","slug":"mareco-chone","status":"publish","type":"product","link":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/mareco-chone\/","title":{"rendered":"Mareco Chone"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><strong>Caratteristiche tecniche<\/strong><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs4306042E\">\u00a0<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs4306042E\">\u00a0<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs4306042E\">\u00a0<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs55EEAEFF\">Led effettivo &#8211; Ta 25\u00b0C<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csC8F6D76\">8W &#8211; 4000K &#8211;\u00a0<\/span><span class=\"cs4306042E\">793 lm<\/span><span class=\"csC8F6D76\">\u00a0&#8211; 220-240V 50\/60Hz<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csC8F6D76\">8W &#8211; 3000K &#8211;\u00a0<\/span><span class=\"cs4306042E\">793 lm<\/span><span class=\"csC8F6D76\">\u00a0&#8211; 220-240V 50\/60Hz<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csC8F6D76\">\u00a0<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs4306042E\">Step MacAdam 3<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs4306042E\">\u00a0<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs4306042E\">Lifetime:<\/span><span class=\"csC8F6D76\">\u00a0L70\/B50=56Kh &#8211; Tc 85\u00b0C<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csC8F6D76\">\u00a0<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs55EEAEFF\">Dati tecnici<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csC8F6D76\">&#8211; Apparecchio per utilizzo su pali \u00d860mm<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csC8F6D76\">&#8211; Guarnizioni in silicone<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csC8F6D76\">&#8211; Verniciatura con pretrattamento specifico per esterni<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csC8F6D76\">&#8211; Viteria in acciaio inox A2<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csC8F6D76\">&#8211; Led posizionato sotto il cappello per il recupero totale di luce<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csC8F6D76\">&#8211; Conforme alle leggi regionali contro l&#8217;inquinamento luminoso<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csC8F6D76\">&#8211; Sopressore integrato per i disturbi di rete<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs102784\">&#8211; Lampada non inclusa<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csC8F6D76\">\u00a0<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs55EEAEFF\">Cappello<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csC8F6D76\">&#8211; Cappello in tecnopolimero rinforzato verniciato<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csC8F6D76\">\u00a0<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs55EEAEFF\">Diffusore<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csC8F6D76\">&#8211; Diffusore in PMMA (acrilico) trasparente inalterabile ai raggi UV prismatizzato internamente<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csC8F6D76\">\u00a0<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs55EEAEFF\">Cono<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csC8F6D76\">&#8211; Cono diffusore in PC (policarbonato) bianco<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csC8F6D76\">\u00a0<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs55EEAEFF\">Corpo<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csC8F6D76\">&#8211; Corpo in tecnopolimero rinforzato verniciato<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csC8F6D76\">\u00a0<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csD491EB\">Accessori opzionali per l&#8217;installazione<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs102784\">(da ordinare separatamente)<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs23FB0664\">&#8211; Morsettiera IP68<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs23FB0664\">&#8211; Morsettiera &#8220;T&#8221; IP68<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs23FB0664\">&#8211; Mistral<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs23FB0664\">&#8211; Mistral grigio metallizzato RAL 9006<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs23FB0664\">\u00a0<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"csD491EB\">Pali consigliati per l&#8217;installazione<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs102784\">(da ordinare separatamente)<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs23FB0664\">&#8211; Full black<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs23FB0664\">&#8211; Full color grigio metallizzato RAL 9006<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs23FB0664\">&#8211; Slick<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs23FB0664\">&#8211; Slick grigio metallizzato RAL 9006<\/span><\/p>\n<p class=\"cs2654AE3A\"><span class=\"cs23FB0664\">&#8211; Rigo<\/span><\/p>\n<div class=\"scheda-prodotto\"><a href=\"http:\/\/www.marecoluce.it\/it\/prodotti\/LED\/Residenziale\/Chone\/32123\/search.aspx#backgroundOverlay\" target=\"_blank\" rel=\"noopener\">Vai alla scheda prodotto<\/a><\/div>\n<div>\n<p>Dove acquistare Mareco da Vegliolux, un marchio del gruppo Idrocentro:<\/p>\n<p>Piemonte:<\/p>\n<p>\u2013 Torino:<br \/>\n\u2014 Filiale principale: Via Sandro Botticelli, 151\/a, 10154 Torino TO<br \/>\n\u2014 Orbassano: Corso Orbassano, 400, 10137 Torino TO<br \/>\n\u2014 Centro: Corso Sommeiller, 15\/D, 10128 Torino TO<br \/>\n\u2014 Corso Lecce: Corso Lecce, 56, 10143 Torino TO<\/p>\n<p>\u2013 Volpiano: Via Venezia, 12, 10088 Volpiano TO<\/p>\n<p>\u2013 Asti Ovest: Corso Torino, 43, 14100 Asti AT<\/p>\n<p>\u2013 Borgaretto: Via Rond\u00f2 Bernardo, 30, 10092 Beinasco TO<\/p>\n<p>\u2013 Borgo Gesso: Via Torre Acceglio, 26, 12100 Cuneo CN<\/p>\n<p>\u2013 Carmagnola: Via Sommariva, 14, 10022 Carmagnola TO<\/p>\n<p>\u2013 Caselle: Str. Ciri\u00e8, 175, 10072 Caselle torinese TO<\/p>\n<p>\u2013 Chieri: Via XXV Aprile, 8, 10023 Chieri TO<\/p>\n<p>\u2013 Pinerolo: Via Saluzzo, 165, 10064 Pinerolo TO<\/p>\n<p>\u2013 Settimo: Str. S. Giorgio, 43, 10036 Settimo Torinese TO<\/p>\n<p>\u2013 Susa: Corso Stati Uniti, 89, 10059 Susa TO<\/p>\n<p>\u2013 Torre San Giorgio: Via Circonvallazione G. Giolitti, 100, 12030 Torre San Giorgio CN (Sede gruppo Idrocentro)<\/p>\n<p>\u2013 Castelnuovo Calcea: Via Opessina, 14040 Castenuovo Calcea, AT<\/p>\n<p>Liguria:<\/p>\n<p>\u2013 Genova Sturla: Via Tabarca, 44, 16147 Genova GE<\/p>\n<p>\u2013 Vado Ligure: Via Leopardi, 4, 17047 Vado Ligure SV<\/p>\n<p>\u2013 Andora: Via Merula, 22, 17051 Andora SV<\/p>\n<p>Lombardia:<\/p>\n<p>\u2013 Cornaredo: Via Napoli, 7, 20010 Cornaredo MI<\/p>\n<p>Valle d&#8217;Aosta:<\/p>\n<p>\u2013 Quart: Localit\u00e0 Amerique, 3, 11100 Villair-Amerique AO<\/p>\n<\/div>\n","protected":false},"featured_media":7972,"template":"","meta":[],"product_brand":[],"product_cat":[155,281],"product_tag":[185],"class_list":{"0":"post-7971","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-esterno-residenziale","7":"product_cat-mareco","8":"product_tag-mareco-luce","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mareco Chone - Vegliolux<\/title>\n<meta name=\"description\" content=\"Da Vegliolux, un marchio del gruppo Idrocentro, puoi trovare Mareco Chone . Da Vegliolux la migliore illuminazione\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/mareco-chone\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mareco Chone - Vegliolux\" \/>\n<meta property=\"og:description\" content=\"Da Vegliolux, un marchio del gruppo Idrocentro, puoi trovare Mareco Chone . Da Vegliolux la migliore illuminazione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/mareco-chone\/\" \/>\n<meta property=\"og:site_name\" content=\"Vegliolux\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vegliolux\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-25T09:05:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2018\/07\/Mareco-Chone-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"973\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/mareco-chone\\\/\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/mareco-chone\\\/\",\"name\":\"Mareco Chone - Vegliolux\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/mareco-chone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/mareco-chone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Mareco-Chone-01.jpg\",\"datePublished\":\"2018-07-11T14:00:40+00:00\",\"dateModified\":\"2023-08-25T09:05:42+00:00\",\"description\":\"Da Vegliolux, un marchio del gruppo Idrocentro, puoi trovare Mareco Chone . Da Vegliolux la migliore illuminazione\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/mareco-chone\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/mareco-chone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/mareco-chone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Mareco-Chone-01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Mareco-Chone-01.jpg\",\"width\":800,\"height\":973,\"caption\":\"Mareco Chone Solar: luce da esterno da Vegliolux, un marchio del gruppo Idrocentro, gli specialisti di illuminazione e elettroforniture. Acquista nei nostri punti vendita di Piemonte, Liguria, Lombardia e Valle d'Aosta\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/mareco-chone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mareco Chone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#website\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/\",\"name\":\"Vegliolux - Illuminazione Torino\",\"description\":\"Emozioni luminose\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#organization\",\"name\":\"Vegliolux - Illuminazione Torino\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Vegliolux-Sommeiller.jpg\",\"contentUrl\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Vegliolux-Sommeiller.jpg\",\"width\":1080,\"height\":720,\"caption\":\"Vegliolux - Illuminazione Torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vegliolux\",\"https:\\\/\\\/www.instagram.com\\\/vegliolux\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vegliolux\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mareco Chone - Vegliolux","description":"Da Vegliolux, un marchio del gruppo Idrocentro, puoi trovare Mareco Chone . Da Vegliolux la migliore illuminazione","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/mareco-chone\/","og_locale":"it_IT","og_type":"article","og_title":"Mareco Chone - Vegliolux","og_description":"Da Vegliolux, un marchio del gruppo Idrocentro, puoi trovare Mareco Chone . Da Vegliolux la migliore illuminazione","og_url":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/mareco-chone\/","og_site_name":"Vegliolux","article_publisher":"https:\/\/www.facebook.com\/Vegliolux","article_modified_time":"2023-08-25T09:05:42+00:00","og_image":[{"width":800,"height":973,"url":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2018\/07\/Mareco-Chone-01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/mareco-chone\/","url":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/mareco-chone\/","name":"Mareco Chone - Vegliolux","isPartOf":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/mareco-chone\/#primaryimage"},"image":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/mareco-chone\/#primaryimage"},"thumbnailUrl":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2018\/07\/Mareco-Chone-01.jpg","datePublished":"2018-07-11T14:00:40+00:00","dateModified":"2023-08-25T09:05:42+00:00","description":"Da Vegliolux, un marchio del gruppo Idrocentro, puoi trovare Mareco Chone . Da Vegliolux la migliore illuminazione","breadcrumb":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/mareco-chone\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/mareco-chone\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/mareco-chone\/#primaryimage","url":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2018\/07\/Mareco-Chone-01.jpg","contentUrl":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2018\/07\/Mareco-Chone-01.jpg","width":800,"height":973,"caption":"Mareco Chone Solar: luce da esterno da Vegliolux, un marchio del gruppo Idrocentro, gli specialisti di illuminazione e elettroforniture. Acquista nei nostri punti vendita di Piemonte, Liguria, Lombardia e Valle d'Aosta"},{"@type":"BreadcrumbList","@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/mareco-chone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.veglio.com\/emozioniluminose\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/www.veglio.com\/emozioniluminose\/prodotti\/"},{"@type":"ListItem","position":3,"name":"Mareco Chone"}]},{"@type":"WebSite","@id":"https:\/\/www.veglio.com\/emozioniluminose\/#website","url":"https:\/\/www.veglio.com\/emozioniluminose\/","name":"Vegliolux - Illuminazione Torino","description":"Emozioni luminose","publisher":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.veglio.com\/emozioniluminose\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.veglio.com\/emozioniluminose\/#organization","name":"Vegliolux - Illuminazione Torino","url":"https:\/\/www.veglio.com\/emozioniluminose\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.veglio.com\/emozioniluminose\/#\/schema\/logo\/image\/","url":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2022\/09\/Vegliolux-Sommeiller.jpg","contentUrl":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2022\/09\/Vegliolux-Sommeiller.jpg","width":1080,"height":720,"caption":"Vegliolux - Illuminazione Torino"},"image":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vegliolux","https:\/\/www.instagram.com\/vegliolux\/","https:\/\/www.linkedin.com\/company\/vegliolux"]}]}},"_links":{"self":[{"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product\/7971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/media\/7972"}],"wp:attachment":[{"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/media?parent=7971"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product_brand?post=7971"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product_cat?post=7971"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product_tag?post=7971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}