{"id":8240,"date":"2018-07-18T15:04:52","date_gmt":"2018-07-18T13:04:52","guid":{"rendered":"http:\/\/beta.veglio.com\/emozioniluminose\/?post_type=product&#038;p=8240"},"modified":"2023-08-25T09:56:22","modified_gmt":"2023-08-25T07:56:22","slug":"creative-cable-cavo-elettrico-rm04","status":"publish","type":"product","link":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/creative-cable-cavo-elettrico-rm04\/","title":{"rendered":"Creative-Cable Cavo Elettrico RM04"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>I nostri cavi elettrici in tessuto effetto seta, sono ideali per i progetti di illuminazione con un look moderno ed elegante.<br \/>\nIl cavo elettrico in tessuto Effetto Seta Nero RM04, presenta un colore lucido e brillante.<br \/>\nI fili elettrici colorati Creative-Cables sono perfetti per ideare lampade di design, rinnovare un abat-jour, dare un tocco di colore alla vostra casa o al vostro ufficio e sono realizzati al 100% in Italia.<\/p>\n<div class=\"scheda-prodotto\"><a href=\"https:\/\/www.creative-cables.it\/cavi-per-illuminazione\/1391-cavo-elettrico-rotondo-rivestito-in-tessuto-effetto-seta-tinta-unita-nero-rm04.html\" target=\"_blank\" rel=\"noopener\">Vai alla scheda prodotto<\/a><\/div>\n<div>\n<p>Dove acquistare Creative Cables da Vegliolux, un marchio del gruppo Idrocentro:<\/p>\n<p>Piemonte:<\/p>\n<p>\u2013 Torino:<\/p>\n<p>\u2014 Filiale principale: Via Sandro Botticelli, 151\/a, 10154 Torino TO<\/p>\n<p>\u2014 Orbassano: Corso Orbassano, 400, 10137 Torino TO<\/p>\n<p>\u2014 Centro: Corso Sommeiller, 15\/D, 10128 Torino TO<\/p>\n<p>\u2014 Corso Lecce: Corso Lecce, 56, 10143 Torino TO<\/p>\n<p>\u2013 Volpiano: Via Venezia, 12, 10088 Volpiano TO<\/p>\n<p>\u2013 Asti Ovest: Corso Torino, 43, 14100 Asti AT<\/p>\n<p>\u2013 Borgaretto: Via Rond\u00f2 Bernardo, 30, 10092 Beinasco TO<\/p>\n<p>\u2013 Borgo Gesso: Via Torre Acceglio, 26, 12100 Cuneo CN<\/p>\n<p>\u2013 Carmagnola: Via Sommariva, 14, 10022 Carmagnola TO<\/p>\n<p>\u2013 Caselle: Str. Ciri\u00e8, 175, 10072 Caselle torinese TO<\/p>\n<p>\u2013 Chieri: Via XXV Aprile, 8, 10023 Chieri TO<\/p>\n<p>\u2013 Pinerolo: Via Saluzzo, 165, 10064 Pinerolo TO<\/p>\n<p>\u2013 Settimo: Str. S. Giorgio, 43, 10036 Settimo Torinese TO<\/p>\n<p>\u2013 Susa: Corso Stati Uniti, 89, 10059 Susa TO<\/p>\n<p>\u2013 Torre San Giorgio: Via Circonvallazione G. Giolitti, 100, 12030 Torre San Giorgio CN (Sede gruppo Idrocentro)<\/p>\n<p>\u2013 Castelnuovo Calcea: Via Opessina, 14040 Castenuovo Calcea, AT<\/p>\n<p>Liguria:<\/p>\n<p>\u2013 Genova Sturla: Via Tabarca, 44, 16147 Genova GE<\/p>\n<p>\u2013 Vado Ligure: Via Leopardi, 4, 17047 Vado Ligure SV<\/p>\n<p>\u2013 Andora: Via Merula, 22, 17051 Andora SV<\/p>\n<p>Lombardia:<\/p>\n<p>\u2013 Cornaredo: Via Napoli, 7, 20010 Cornaredo MI<\/p>\n<p>Valle d&#8217;Aosta:<\/p>\n<p>\u2013 Quart: Localit\u00e0 Amerique, 3, 11100 Villair-Amerique AO<\/p>\n<\/div>\n","protected":false},"featured_media":8241,"template":"","meta":[],"product_brand":[],"product_cat":[260,145],"product_tag":[207],"class_list":{"0":"post-8240","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-creative-cables","7":"product_cat-decorativa-e-design","8":"product_tag-creative-cables","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Creative-Cable Cavo Elettrico RM04 - Vegliolux<\/title>\n<meta name=\"description\" content=\"Da Vegliolux, un marchio del gruppo Idrocentro, puoi trovare Creative-Cable Cavo Elettrico RM04 . Da Vegliolux la migliore illuminazione\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/creative-cable-cavo-elettrico-rm04\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Creative-Cable Cavo Elettrico RM04 - Vegliolux\" \/>\n<meta property=\"og:description\" content=\"Da Vegliolux, un marchio del gruppo Idrocentro, puoi trovare Creative-Cable Cavo Elettrico RM04 . Da Vegliolux la migliore illuminazione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/creative-cable-cavo-elettrico-rm04\/\" \/>\n<meta property=\"og:site_name\" content=\"Vegliolux\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vegliolux\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-25T07:56:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2018\/07\/Creative-Cable-Cavo-Elettrico-RM04-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"973\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/creative-cable-cavo-elettrico-rm04\\\/\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/creative-cable-cavo-elettrico-rm04\\\/\",\"name\":\"Creative-Cable Cavo Elettrico RM04 - Vegliolux\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/creative-cable-cavo-elettrico-rm04\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/creative-cable-cavo-elettrico-rm04\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Creative-Cable-Cavo-Elettrico-RM04-01.jpg\",\"datePublished\":\"2018-07-18T13:04:52+00:00\",\"dateModified\":\"2023-08-25T07:56:22+00:00\",\"description\":\"Da Vegliolux, un marchio del gruppo Idrocentro, puoi trovare Creative-Cable Cavo Elettrico RM04 . Da Vegliolux la migliore illuminazione\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/creative-cable-cavo-elettrico-rm04\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/creative-cable-cavo-elettrico-rm04\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/creative-cable-cavo-elettrico-rm04\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Creative-Cable-Cavo-Elettrico-RM04-01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/Creative-Cable-Cavo-Elettrico-RM04-01.jpg\",\"width\":800,\"height\":973,\"caption\":\"Creative Cable Cavo Elettrico RM04: da Vegliolux by Idrocentro trovi il cavo adatto per ogni gusto estetico\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/creative-cable-cavo-elettrico-rm04\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Creative-Cable Cavo Elettrico RM04\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#website\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/\",\"name\":\"Vegliolux - Illuminazione Torino\",\"description\":\"Emozioni luminose\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#organization\",\"name\":\"Vegliolux - Illuminazione Torino\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Vegliolux-Sommeiller.jpg\",\"contentUrl\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Vegliolux-Sommeiller.jpg\",\"width\":1080,\"height\":720,\"caption\":\"Vegliolux - Illuminazione Torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vegliolux\",\"https:\\\/\\\/www.instagram.com\\\/vegliolux\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vegliolux\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Creative-Cable Cavo Elettrico RM04 - Vegliolux","description":"Da Vegliolux, un marchio del gruppo Idrocentro, puoi trovare Creative-Cable Cavo Elettrico RM04 . Da Vegliolux la migliore illuminazione","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/creative-cable-cavo-elettrico-rm04\/","og_locale":"it_IT","og_type":"article","og_title":"Creative-Cable Cavo Elettrico RM04 - Vegliolux","og_description":"Da Vegliolux, un marchio del gruppo Idrocentro, puoi trovare Creative-Cable Cavo Elettrico RM04 . Da Vegliolux la migliore illuminazione","og_url":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/creative-cable-cavo-elettrico-rm04\/","og_site_name":"Vegliolux","article_publisher":"https:\/\/www.facebook.com\/Vegliolux","article_modified_time":"2023-08-25T07:56:22+00:00","og_image":[{"width":800,"height":973,"url":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2018\/07\/Creative-Cable-Cavo-Elettrico-RM04-01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/creative-cable-cavo-elettrico-rm04\/","url":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/creative-cable-cavo-elettrico-rm04\/","name":"Creative-Cable Cavo Elettrico RM04 - Vegliolux","isPartOf":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/creative-cable-cavo-elettrico-rm04\/#primaryimage"},"image":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/creative-cable-cavo-elettrico-rm04\/#primaryimage"},"thumbnailUrl":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2018\/07\/Creative-Cable-Cavo-Elettrico-RM04-01.jpg","datePublished":"2018-07-18T13:04:52+00:00","dateModified":"2023-08-25T07:56:22+00:00","description":"Da Vegliolux, un marchio del gruppo Idrocentro, puoi trovare Creative-Cable Cavo Elettrico RM04 . Da Vegliolux la migliore illuminazione","breadcrumb":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/creative-cable-cavo-elettrico-rm04\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/creative-cable-cavo-elettrico-rm04\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/creative-cable-cavo-elettrico-rm04\/#primaryimage","url":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2018\/07\/Creative-Cable-Cavo-Elettrico-RM04-01.jpg","contentUrl":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2018\/07\/Creative-Cable-Cavo-Elettrico-RM04-01.jpg","width":800,"height":973,"caption":"Creative Cable Cavo Elettrico RM04: da Vegliolux by Idrocentro trovi il cavo adatto per ogni gusto estetico"},{"@type":"BreadcrumbList","@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/creative-cable-cavo-elettrico-rm04\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.veglio.com\/emozioniluminose\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/www.veglio.com\/emozioniluminose\/prodotti\/"},{"@type":"ListItem","position":3,"name":"Creative-Cable Cavo Elettrico RM04"}]},{"@type":"WebSite","@id":"https:\/\/www.veglio.com\/emozioniluminose\/#website","url":"https:\/\/www.veglio.com\/emozioniluminose\/","name":"Vegliolux - Illuminazione Torino","description":"Emozioni luminose","publisher":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.veglio.com\/emozioniluminose\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.veglio.com\/emozioniluminose\/#organization","name":"Vegliolux - Illuminazione Torino","url":"https:\/\/www.veglio.com\/emozioniluminose\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.veglio.com\/emozioniluminose\/#\/schema\/logo\/image\/","url":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2022\/09\/Vegliolux-Sommeiller.jpg","contentUrl":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2022\/09\/Vegliolux-Sommeiller.jpg","width":1080,"height":720,"caption":"Vegliolux - Illuminazione Torino"},"image":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vegliolux","https:\/\/www.instagram.com\/vegliolux\/","https:\/\/www.linkedin.com\/company\/vegliolux"]}]}},"_links":{"self":[{"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product\/8240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/media\/8241"}],"wp:attachment":[{"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/media?parent=8240"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product_brand?post=8240"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product_cat?post=8240"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product_tag?post=8240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}