{"id":87680,"date":"2021-07-29T09:29:21","date_gmt":"2021-07-29T07:29:21","guid":{"rendered":"https:\/\/www.veglio.com\/emozioniluminose\/?post_type=product&#038;p=87680"},"modified":"2023-08-25T11:38:32","modified_gmt":"2023-08-25T09:38:32","slug":"tec-mar-polar","status":"publish","type":"product","link":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tec-mar-polar\/","title":{"rendered":"Tec-Mar Polar"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<div class=\"ctg-post-text left col-xs-12 col-md-6\">\n<div id=\"caratteristiche_principali\">\n<div class=\"row no-gutters\">\n<div class=\"col-5 col-md-5 col-lg-3\">\n<div id=\"caratteristiche_principali\">\n<div class=\"row no-gutters\">\n<div class=\"col-5 col-md-5 col-lg-3\">\n<div id=\"caratteristiche_principali\">\n<div class=\"row no-gutters\">\n<div class=\"col-5 col-md-5 col-lg-3\">\n<div id=\"caratteristiche_principali\">\n<div class=\"row no-gutters\">\n<div class=\"col-5 col-md-5 col-lg-3\">\n<div id=\"caratteristiche_principali\">\n<div class=\"row no-gutters\">\n<div class=\"col-5 col-md-5 col-lg-3\">\n<div class=\"vc_row wpb_row section vc_row-fluid \">\n<div class=\" full_section_inner clearfix\">\n<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n<div class=\"vc_column-inner \">\n<div class=\"wpb_wrapper\">\n<h1 class=\"product_title entry-title\">ART. 7029.POLAR 4\/AR<\/h1>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_row wpb_row section vc_row-fluid \">\n<div class=\" full_section_inner clearfix\">\n<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n<div class=\"vc_column-inner \">\n<div class=\"wpb_wrapper\">\n<div class=\"duecolonne\">\n<table class=\"shop_attributes\">\n<tbody>\n<tr>\n<th>MODELLO<\/th>\n<td>AR<\/td>\n<\/tr>\n<tr>\n<th>CLASSE DI ISOLAMENTO<\/th>\n<td>Classe I<\/td>\n<\/tr>\n<tr>\n<th>MATERIALI<\/th>\n<td>Corpo in alluminio pressofuso verniciato con polvere termoindurente poliestere anticorrosione colore silver, vetro temperato trasparente spessore 4 mm, guarnizione in silicone<\/td>\n<\/tr>\n<tr>\n<th>OTTICA<\/th>\n<td>Riflettore asimmetrico 45\u00b0 in alluminio satinato<\/td>\n<\/tr>\n<tr>\n<th>INSTALLAZIONE<\/th>\n<td>Apparecchio adatto per installazione a terra, a soffitto, a parete, su palo 60mm.<\/td>\n<\/tr>\n<tr>\n<th>GRADO DI PROTEZIONE<\/th>\n<td>IP66<\/td>\n<\/tr>\n<tr>\n<th>PROTEZIONE CONTRO GLI URTI<\/th>\n<td>IK08<\/td>\n<\/tr>\n<tr>\n<th>TA AMBIENTE<\/th>\n<td>-25 \/ +45 \u00b0C<\/td>\n<\/tr>\n<tr>\n<th>TENSIONE NOMINALE<\/th>\n<td>220-240Vac 50\/60Hz<\/td>\n<\/tr>\n<tr>\n<th>FLICKER<\/th>\n<td>low Flicker (minore del 7%)<\/td>\n<\/tr>\n<tr>\n<th>MARCHI E CERTIFICAZIONI<\/th>\n<td>CE \/ UNI EN 60598-1:2015<\/td>\n<\/tr>\n<tr>\n<th>GARANZIA<\/th>\n<td>7 ANNI<\/td>\n<\/tr>\n<tr>\n<th>INDICE DI DECADIMENTO FLUSSO<\/th>\n<td>L90-B10 (50.000h)-L80-B50 (90.000h)<\/td>\n<\/tr>\n<tr>\n<th>RISCHIO FOTOBIOLOGICO<\/th>\n<td>Gruppo rischio esente<\/td>\n<\/tr>\n<tr>\n<th>ANGOLO<\/th>\n<td>45\u00b0<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"social_share\">\n<div><\/div>\n<div class=\"social_icons active\">Dove acquistare Tec-Mar da Vegliolux, un marchio del gruppo Idrocentro:<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Piemonte:<\/p>\n<p>\u2013 Torino:<br \/>\n\u2014 Filiale principale: Via Sandro Botticelli, 151\/a, 10154 Torino TO<br \/>\n\u2014 Orbassano: Corso Orbassano, 400, 10137 Torino TO<br \/>\n\u2014 Centro: Corso Sommeiller, 15\/D, 10128 Torino TO<br \/>\n\u2014 Corso Lecce: Corso Lecce, 56, 10143 Torino TO<\/p>\n<p>\u2013 Volpiano: Via Venezia, 12, 10088 Volpiano TO<\/p>\n<p>\u2013 Asti Ovest: Corso Torino, 43, 14100 Asti AT<\/p>\n<p>\u2013 Borgaretto: Via Rond\u00f2 Bernardo, 30, 10092 Beinasco TO<\/p>\n<p>\u2013 Borgo Gesso: Via Torre Acceglio, 26, 12100 Cuneo CN<\/p>\n<p>\u2013 Carmagnola: Via Sommariva, 14, 10022 Carmagnola TO<\/p>\n<p>\u2013 Caselle: Str. Ciri\u00e8, 175, 10072 Caselle torinese TO<\/p>\n<p>\u2013 Chieri: Via XXV Aprile, 8, 10023 Chieri TO<\/p>\n<p>\u2013 Pinerolo: Via Saluzzo, 165, 10064 Pinerolo TO<\/p>\n<p>\u2013 Settimo: Str. S. Giorgio, 43, 10036 Settimo Torinese TO<\/p>\n<p>\u2013 Susa: Corso Stati Uniti, 89, 10059 Susa TO<\/p>\n<p>\u2013 Torre San Giorgio: Via Circonvallazione G. Giolitti, 100, 12030 Torre San Giorgio CN (Sede gruppo Idrocentro)<\/p>\n<p>Liguria:<\/p>\n<p>\u2013 Genova Sturla: Via Tabarca, 44, 16147 Genova GE<\/p>\n<p>\u2013 Vado Ligure: Via Leopardi, 4, 17047 Vado Ligure SV<\/p>\n<p>\u2013 Andora: Via Merula, 22, 17051 Andora SV<\/p>\n<p>Lombardia:<\/p>\n<p>\u2013 Cornaredo: Via Napoli, 7, 20010 Cornaredo MI<\/p>\n<p>Valle d&#8217;Aosta:<\/p>\n<p>\u2013 Quart: Localit\u00e0 Amerique, 3, 11100 Villair-Amerique AO<\/p>\n<p><a href=\"https:\/\/www.tec-mar.it\/prodotto\/art-7029-polar-4-ar\/?format=pdf\">Scheda prodotto<\/a><\/p>\n","protected":false},"featured_media":87681,"template":"","meta":[],"product_brand":[],"product_cat":[144,157,296],"product_tag":[218],"class_list":{"0":"post-87680","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-parete","7":"product_cat-proiettori","8":"product_cat-tecmar","9":"product_tag-tec-mar","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tec-Mar Polar - Vegliolux specialisti dell&#039;Illuminazione<\/title>\n<meta name=\"description\" content=\"Da Vegliolux, un marchio del gruppo Idrocentro, l&#039;apparecchio di terra, soffitto di Tec-Mar. Da Vegliolux la migliore illuminazione\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tec-mar-polar\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tec-Mar Polar - Vegliolux specialisti dell&#039;Illuminazione\" \/>\n<meta property=\"og:description\" content=\"Da Vegliolux, un marchio del gruppo Idrocentro, l&#039;apparecchio di terra, soffitto di Tec-Mar. Da Vegliolux la migliore illuminazione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tec-mar-polar\/\" \/>\n<meta property=\"og:site_name\" content=\"Vegliolux\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vegliolux\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-25T09:38:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2021\/07\/Polar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"973\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/tec-mar-polar\\\/\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/tec-mar-polar\\\/\",\"name\":\"Tec-Mar Polar - Vegliolux specialisti dell'Illuminazione\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/tec-mar-polar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/tec-mar-polar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Polar.jpg\",\"datePublished\":\"2021-07-29T07:29:21+00:00\",\"dateModified\":\"2023-08-25T09:38:32+00:00\",\"description\":\"Da Vegliolux, un marchio del gruppo Idrocentro, l'apparecchio di terra, soffitto di Tec-Mar. Da Vegliolux la migliore illuminazione\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/tec-mar-polar\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/tec-mar-polar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/tec-mar-polar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Polar.jpg\",\"contentUrl\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Polar.jpg\",\"width\":800,\"height\":973,\"caption\":\"Tec-Mar Polar: lampada da parete Piemonte, Liguria nei punti vendita di Vegliolux, un marchio del gruppo Idrocentro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/tec-mar-polar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tec-Mar Polar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#website\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/\",\"name\":\"Vegliolux - Illuminazione Torino\",\"description\":\"Emozioni luminose\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#organization\",\"name\":\"Vegliolux - Illuminazione Torino\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Vegliolux-Sommeiller.jpg\",\"contentUrl\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Vegliolux-Sommeiller.jpg\",\"width\":1080,\"height\":720,\"caption\":\"Vegliolux - Illuminazione Torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vegliolux\",\"https:\\\/\\\/www.instagram.com\\\/vegliolux\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vegliolux\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tec-Mar Polar - Vegliolux specialisti dell'Illuminazione","description":"Da Vegliolux, un marchio del gruppo Idrocentro, l'apparecchio di terra, soffitto di Tec-Mar. Da Vegliolux la migliore illuminazione","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tec-mar-polar\/","og_locale":"it_IT","og_type":"article","og_title":"Tec-Mar Polar - Vegliolux specialisti dell'Illuminazione","og_description":"Da Vegliolux, un marchio del gruppo Idrocentro, l'apparecchio di terra, soffitto di Tec-Mar. Da Vegliolux la migliore illuminazione","og_url":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tec-mar-polar\/","og_site_name":"Vegliolux","article_publisher":"https:\/\/www.facebook.com\/Vegliolux","article_modified_time":"2023-08-25T09:38:32+00:00","og_image":[{"width":800,"height":973,"url":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2021\/07\/Polar.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tec-mar-polar\/","url":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tec-mar-polar\/","name":"Tec-Mar Polar - Vegliolux specialisti dell'Illuminazione","isPartOf":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tec-mar-polar\/#primaryimage"},"image":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tec-mar-polar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2021\/07\/Polar.jpg","datePublished":"2021-07-29T07:29:21+00:00","dateModified":"2023-08-25T09:38:32+00:00","description":"Da Vegliolux, un marchio del gruppo Idrocentro, l'apparecchio di terra, soffitto di Tec-Mar. Da Vegliolux la migliore illuminazione","breadcrumb":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tec-mar-polar\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tec-mar-polar\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tec-mar-polar\/#primaryimage","url":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2021\/07\/Polar.jpg","contentUrl":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2021\/07\/Polar.jpg","width":800,"height":973,"caption":"Tec-Mar Polar: lampada da parete Piemonte, Liguria nei punti vendita di Vegliolux, un marchio del gruppo Idrocentro"},{"@type":"BreadcrumbList","@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tec-mar-polar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.veglio.com\/emozioniluminose\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/www.veglio.com\/emozioniluminose\/prodotti\/"},{"@type":"ListItem","position":3,"name":"Tec-Mar Polar"}]},{"@type":"WebSite","@id":"https:\/\/www.veglio.com\/emozioniluminose\/#website","url":"https:\/\/www.veglio.com\/emozioniluminose\/","name":"Vegliolux - Illuminazione Torino","description":"Emozioni luminose","publisher":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.veglio.com\/emozioniluminose\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.veglio.com\/emozioniluminose\/#organization","name":"Vegliolux - Illuminazione Torino","url":"https:\/\/www.veglio.com\/emozioniluminose\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.veglio.com\/emozioniluminose\/#\/schema\/logo\/image\/","url":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2022\/09\/Vegliolux-Sommeiller.jpg","contentUrl":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2022\/09\/Vegliolux-Sommeiller.jpg","width":1080,"height":720,"caption":"Vegliolux - Illuminazione Torino"},"image":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vegliolux","https:\/\/www.instagram.com\/vegliolux\/","https:\/\/www.linkedin.com\/company\/vegliolux"]}]}},"_links":{"self":[{"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product\/87680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/media\/87681"}],"wp:attachment":[{"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/media?parent=87680"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product_brand?post=87680"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product_cat?post=87680"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product_tag?post=87680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}