{"id":87686,"date":"2021-07-29T10:14:08","date_gmt":"2021-07-29T08:14:08","guid":{"rendered":"https:\/\/www.veglio.com\/emozioniluminose\/?post_type=product&#038;p=87686"},"modified":"2023-08-25T11:39:27","modified_gmt":"2023-08-25T09:39:27","slug":"tooy-legier","status":"publish","type":"product","link":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tooy-legier\/","title":{"rendered":"Tooy Legier"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<div class=\"ctg-post-text left col-xs-12 col-md-6\">\n<div id=\"caratteristiche_principali\">\n<div class=\"row no-gutters\">\n<div class=\"col-5 col-md-5 col-lg-3\">\n<div id=\"caratteristiche_principali\">\n<div class=\"row no-gutters\">\n<div class=\"col-5 col-md-5 col-lg-3\">\n<div id=\"caratteristiche_principali\">\n<div class=\"row no-gutters\">\n<div class=\"col-5 col-md-5 col-lg-3\">\n<div id=\"caratteristiche_principali\">\n<div class=\"row no-gutters\">\n<div class=\"col-5 col-md-5 col-lg-3\">\n<div id=\"caratteristiche_principali\">\n<div class=\"row no-gutters\">\n<div class=\"col-5 col-md-5 col-lg-3\">\n<div class=\"vc_row wpb_row section vc_row-fluid \">\n<div class=\" full_section_inner clearfix\">\n<div class=\"wpb_column vc_column_container vc_col-sm-12\"><\/div>\n<\/div>\n<\/div>\n<div class=\"social_share\">\n<div>\n<p>Collezioni di lampade ispirate dalle forme delle classiche lampade di Murano, diffusori normalmente usati per decorare qualsiasi stanza della casa; eleganti, sferiche e apparentemente fragili ma molto robuste e funzionali. Queste lampade hanno la connessione in rame galvanico, ottone dipinto, mentre il diffusore \u00e8 fatto di vetro soffiato, vetro opalizzato bianco o fum\u00e8, con forme armoniose o decorative.<\/p>\n<p>Versatili, eleganti e robuste, queste lampade possono essere posizionate sul pavimento, sul tavolo, sul soffitto, sui muri o in sospensione singola o in candelabro da quattro a sei elementi. Queste lampade conferiscono un aspetto di classe e sofisticato a qualsiasi luogo, che sia sobrio o sontuoso.<\/p>\n<\/div>\n<div class=\"social_icons active\">Dove acquistare Tooy da Vegliolux, un marchio del gruppo Idrocentro:<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Piemonte:<\/p>\n<p>\u2013 Torino:<br \/>\n\u2014 Filiale principale: Via Sandro Botticelli, 151\/a, 10154 Torino TO<br \/>\n\u2014 Orbassano: Corso Orbassano, 400, 10137 Torino TO<br \/>\n\u2014 Centro: Corso Sommeiller, 15\/D, 10128 Torino TO<br \/>\n\u2014 Corso Lecce: Corso Lecce, 56, 10143 Torino TO<\/p>\n<p>\u2013 Volpiano: Via Venezia, 12, 10088 Volpiano TO<\/p>\n<p>\u2013 Asti Ovest: Corso Torino, 43, 14100 Asti AT<\/p>\n<p>\u2013 Borgaretto: Via Rond\u00f2 Bernardo, 30, 10092 Beinasco TO<\/p>\n<p>\u2013 Borgo Gesso: Via Torre Acceglio, 26, 12100 Cuneo CN<\/p>\n<p>\u2013 Carmagnola: Via Sommariva, 14, 10022 Carmagnola TO<\/p>\n<p>\u2013 Caselle: Str. Ciri\u00e8, 175, 10072 Caselle torinese TO<\/p>\n<p>\u2013 Chieri: Via XXV Aprile, 8, 10023 Chieri TO<\/p>\n<p>\u2013 Pinerolo: Via Saluzzo, 165, 10064 Pinerolo TO<\/p>\n<p>\u2013 Settimo: Str. S. Giorgio, 43, 10036 Settimo Torinese TO<\/p>\n<p>\u2013 Susa: Corso Stati Uniti, 89, 10059 Susa TO<\/p>\n<p>\u2013 Torre San Giorgio: Via Circonvallazione G. Giolitti, 100, 12030 Torre San Giorgio CN (Sede gruppo Idrocentro)<\/p>\n<p>Liguria:<\/p>\n<p>\u2013 Genova Sturla: Via Tabarca, 44, 16147 Genova GE<\/p>\n<p>\u2013 Vado Ligure: Via Leopardi, 4, 17047 Vado Ligure SV<\/p>\n<p>\u2013 Andora: Via Merula, 22, 17051 Andora SV<\/p>\n<p>Lombardia:<\/p>\n<p>\u2013 Cornaredo: Via Napoli, 7, 20010 Cornaredo MI<\/p>\n<p>Valle d&#8217;Aosta:<\/p>\n<p>\u2013 Quart: Localit\u00e0 Amerique, 3, 11100 Villair-Amerique AO<\/p>\n<p><a href=\"http:\/\/www.tooy.it\/products\/legier\/557-22\">Scheda prodotto<\/a><\/p>\n","protected":false},"featured_media":87687,"template":"","meta":[],"product_brand":[],"product_cat":[144,139,138,206,297],"product_tag":[235],"class_list":{"0":"post-87686","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-parete","7":"product_cat-soffitto","8":"product_cat-sospensione","9":"product_cat-tavolo","10":"product_cat-tooy","11":"product_tag-tooy","13":"first","14":"instock","15":"shipping-taxable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tooy Legier - Vegliolux specialisti dell&#039;Illuminazione<\/title>\n<meta name=\"description\" content=\"Da Vegliolux, un marchio del gruppo Idrocentro, la sospensione Legier di Tooy. Da Vegliolux la migliore illuminazione\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tooy-legier\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tooy Legier - Vegliolux specialisti dell&#039;Illuminazione\" \/>\n<meta property=\"og:description\" content=\"Da Vegliolux, un marchio del gruppo Idrocentro, la sospensione Legier di Tooy. Da Vegliolux la migliore illuminazione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tooy-legier\/\" \/>\n<meta property=\"og:site_name\" content=\"Vegliolux\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vegliolux\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-25T09:39:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2021\/07\/Legier.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"973\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/tooy-legier\\\/\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/tooy-legier\\\/\",\"name\":\"Tooy Legier - Vegliolux specialisti dell'Illuminazione\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/tooy-legier\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/tooy-legier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Legier.jpg\",\"datePublished\":\"2021-07-29T08:14:08+00:00\",\"dateModified\":\"2023-08-25T09:39:27+00:00\",\"description\":\"Da Vegliolux, un marchio del gruppo Idrocentro, la sospensione Legier di Tooy. Da Vegliolux la migliore illuminazione\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/tooy-legier\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/tooy-legier\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/tooy-legier\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Legier.jpg\",\"contentUrl\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Legier.jpg\",\"width\":800,\"height\":973,\"caption\":\"Tooy Legier: la lampada da sospensione, terra, soffitto, parete Piemonte, Liguria nei punti vendita di Vegliolux, un marchio del gruppo Idrocentro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotto\\\/tooy-legier\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/prodotti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tooy Legier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#website\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/\",\"name\":\"Vegliolux - Illuminazione Torino\",\"description\":\"Emozioni luminose\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#organization\",\"name\":\"Vegliolux - Illuminazione Torino\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Vegliolux-Sommeiller.jpg\",\"contentUrl\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Vegliolux-Sommeiller.jpg\",\"width\":1080,\"height\":720,\"caption\":\"Vegliolux - Illuminazione Torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.veglio.com\\\/emozioniluminose\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vegliolux\",\"https:\\\/\\\/www.instagram.com\\\/vegliolux\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vegliolux\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tooy Legier - Vegliolux specialisti dell'Illuminazione","description":"Da Vegliolux, un marchio del gruppo Idrocentro, la sospensione Legier di Tooy. Da Vegliolux la migliore illuminazione","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tooy-legier\/","og_locale":"it_IT","og_type":"article","og_title":"Tooy Legier - Vegliolux specialisti dell'Illuminazione","og_description":"Da Vegliolux, un marchio del gruppo Idrocentro, la sospensione Legier di Tooy. Da Vegliolux la migliore illuminazione","og_url":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tooy-legier\/","og_site_name":"Vegliolux","article_publisher":"https:\/\/www.facebook.com\/Vegliolux","article_modified_time":"2023-08-25T09:39:27+00:00","og_image":[{"width":800,"height":973,"url":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2021\/07\/Legier.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tooy-legier\/","url":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tooy-legier\/","name":"Tooy Legier - Vegliolux specialisti dell'Illuminazione","isPartOf":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tooy-legier\/#primaryimage"},"image":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tooy-legier\/#primaryimage"},"thumbnailUrl":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2021\/07\/Legier.jpg","datePublished":"2021-07-29T08:14:08+00:00","dateModified":"2023-08-25T09:39:27+00:00","description":"Da Vegliolux, un marchio del gruppo Idrocentro, la sospensione Legier di Tooy. Da Vegliolux la migliore illuminazione","breadcrumb":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tooy-legier\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tooy-legier\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tooy-legier\/#primaryimage","url":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2021\/07\/Legier.jpg","contentUrl":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2021\/07\/Legier.jpg","width":800,"height":973,"caption":"Tooy Legier: la lampada da sospensione, terra, soffitto, parete Piemonte, Liguria nei punti vendita di Vegliolux, un marchio del gruppo Idrocentro"},{"@type":"BreadcrumbList","@id":"https:\/\/www.veglio.com\/emozioniluminose\/prodotto\/tooy-legier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.veglio.com\/emozioniluminose\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/www.veglio.com\/emozioniluminose\/prodotti\/"},{"@type":"ListItem","position":3,"name":"Tooy Legier"}]},{"@type":"WebSite","@id":"https:\/\/www.veglio.com\/emozioniluminose\/#website","url":"https:\/\/www.veglio.com\/emozioniluminose\/","name":"Vegliolux - Illuminazione Torino","description":"Emozioni luminose","publisher":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.veglio.com\/emozioniluminose\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.veglio.com\/emozioniluminose\/#organization","name":"Vegliolux - Illuminazione Torino","url":"https:\/\/www.veglio.com\/emozioniluminose\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.veglio.com\/emozioniluminose\/#\/schema\/logo\/image\/","url":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2022\/09\/Vegliolux-Sommeiller.jpg","contentUrl":"https:\/\/www.veglio.com\/emozioniluminose\/wp-content\/uploads\/2022\/09\/Vegliolux-Sommeiller.jpg","width":1080,"height":720,"caption":"Vegliolux - Illuminazione Torino"},"image":{"@id":"https:\/\/www.veglio.com\/emozioniluminose\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vegliolux","https:\/\/www.instagram.com\/vegliolux\/","https:\/\/www.linkedin.com\/company\/vegliolux"]}]}},"_links":{"self":[{"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product\/87686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/media\/87687"}],"wp:attachment":[{"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/media?parent=87686"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product_brand?post=87686"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product_cat?post=87686"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.veglio.com\/emozioniluminose\/wp-json\/wp\/v2\/product_tag?post=87686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}